{"id":821,"date":"2026-06-12T15:18:49","date_gmt":"2026-06-12T19:18:49","guid":{"rendered":"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/?page_id=821"},"modified":"2026-06-15T16:16:44","modified_gmt":"2026-06-15T20:16:44","slug":"contacto","status":"publish","type":"page","link":"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light wp-duotone-rgb202202202-rgb254254254-1\" style=\"margin-top:0;margin-bottom:0;min-height:174px;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" class=\"wp-block-cover__image-background wp-image-44 size-full\" alt=\"\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/03\/158786.jpg\" style=\"object-position:52% 40%\" data-object-fit=\"cover\" data-object-position=\"52% 40%\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/03\/158786.jpg 2000w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/03\/158786-300x200.jpg 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/03\/158786-1024x682.jpg 1024w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/03\/158786-768x512.jpg 768w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/03\/158786-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\" style=\"background-color:#bdbdbc\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-block-cover-is-layout-constrained\">\n<h1 class=\"wp-block-heading has-text-align-left align-t has-large-font-size\" style=\"font-style:normal;font-weight:700\">Contacto<\/h1>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-flow wp-block-group-is-layout-flow\" style=\"margin-top:0;margin-bottom:0;padding-top:0;padding-bottom:0\">\n<div style=\"width: 100%\"><iframe loading=\"lazy\" width=\"100%\" height=\"600\" frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" style=\"border:0\" allowfullscreen=\"\" src=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyBVizdQeh3udy11xDc5Ao2YStR2gLc-rfc&amp;q=logical%20web&amp;maptype=roadmap&amp;zoom=17\"><a href=\"https:\/\/www.maps.ie\/create-google-map\/\">Embed Google Street View map<\/a><\/iframe><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Contact Information<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Maecenas nec odio et ante tincidunt tempus. Donec vitae sapien ut libero venenatis faucibus. Nullam quis ante. Etiam sit amet orci eget eros faucibus tincidunt. Duis leo. Sed fringilla mauris sit amet nibh. Donec sodales sagittis magna. Sed consequat, leo.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-grid wp-container-core-group-is-layout-e39da43a wp-block-group-is-layout-grid\">\n<div class=\"wp-block-columns contact-group is-layout-flex wp-container-core-columns-is-layout-84f855d9 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column contact-group-icon is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<i class=\"ri-map-pin-fill icon-contact\"><\/i>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-medium-font-size\">ADDRESS<\/h3>\n\n\n\n<p class=\"has-accent-3-color has-text-color has-link-color wp-elements-6715a9c1f8d7f5d832bc97d5bb35e11a wp-block-paragraph\">Goldfield Rd.<br>7685 Rock Maple<br>Honolulu, HI 96815<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns contact-group is-layout-flex wp-container-core-columns-is-layout-84f855d9 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column contact-group-icon is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<i class=\"ri-suitcase-fill icon-contact\"><\/i>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-medium-font-size\">BUSINESS<\/h3>\n\n\n\n<p class=\"has-accent-3-color has-text-color has-link-color wp-elements-eaf6151214cab75cfa5535a4c358e9f3 wp-block-paragraph\">Mon \u2013 Fri :&nbsp;<strong>9 am&nbsp;to 9&nbsp;pm<\/strong><br>Sat :&nbsp;<strong>9 am&nbsp;to 5&nbsp;pm<\/strong><br>Sun :&nbsp;<strong>Closed<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns contact-group is-layout-flex wp-container-core-columns-is-layout-84f855d9 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column contact-group-icon is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<i class=\"ri-mail-fill icon-contact\"><\/i>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-medium-font-size\">EMAIL<\/h3>\n\n\n\n<p class=\"has-accent-3-color has-text-color has-link-color wp-elements-73dc6d7a2bab55c319e387a16e5d54e2 wp-block-paragraph\"><a href=\"mailto:info@camping.com\">info@corporateevents.com<br><\/a><a href=\"mailto:sales@camping.com\">sales@corporateevents.com<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns contact-group is-layout-flex wp-container-core-columns-is-layout-84f855d9 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column contact-group-icon is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<i class=\"ri-phone-fill icon-contact\"><\/i>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-medium-font-size\">PHONE<\/h3>\n\n\n\n<p class=\"has-accent-3-color has-text-color has-link-color wp-elements-d7457c65c8876a6c2874e9472d826fa2 wp-block-paragraph\">+12 0234 567 89<br>+12 0234 567 89<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Enquiry Form<\/h2>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f831-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"831\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tecnologia\/theme-01\/wp-json\/wp\/v2\/pages\/821#wpcf7-f831-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"831\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f831-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required cf-input\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email cf-input\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required cf-input\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Subject\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea cf-textarea\" aria-invalid=\"false\" placeholder=\"Message\" name=\"your-message\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner cf-btn\" type=\"submit\" value=\"SUBMIT\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light has-parallax has-contrast-color has-text-color has-link-color wp-elements-02a6533ec739f91ae6377091ca09c02f\"><div class=\"wp-block-cover__image-background wp-image-834 size-large has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/event-full1-1024x528.jpg)\"><\/div><span aria-hidden=\"true\" class=\"wp-block-cover__background has-base-background-color has-background-dim-80 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-block-cover-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\">Register to Corporate Events Now!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-35f06ea7 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button plan-btn\"><a class=\"wp-block-button__link has-base-color has-accent-1-background-color has-text-color has-background has-link-color has-text-align-center wp-element-button\" style=\"border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;text-transform:capitalize\">REGISTRAR AHORA<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--50);margin-bottom:var(--wp--preset--spacing--50)\">\t\n\t\t<div id=\"gs_logo_area_48\" data-sort=\"name\" data-shortcode-id=\"48\" class=\"gs_logo_area gs_logo_area_48 slider1 \" data-options='{\"logo_per_page\":\"6\"}' style=\"opacity: 0; visibility: hidden;\">\n\t\t\t<div class=\"gs_logo_area--inner\">\n\n\t\t\t\t<!-- Category Filters - New (Global) -->\n\t\t\t\t\t\n\t\t\t\t\n<div class=\"gs_logo_container gs_carousel_swiper gs_logo_fix_height_and_center\" data-carousel-config='{\"direction\":\"horizontal\",\"speed\":500,\"isAutoplay\":true,\"autoplayDelay\":2000,\"loop\":true,\"pauseOnHover\":true,\"ticker\":false,\"navs\":true,\"navs_pos\":\"bottom\",\"dots\":false,\"dynamic_dots\":true,\"slideSpace\":10,\"slidesPerGroup\":1,\"desktopLogos\":5,\"tabletLogos\":3,\"mobileLogos\":2,\"reverseDirection\":false}'>\n\n\t\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-12-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo Twelve\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-12-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-12.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo Twelve<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-2-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo Two\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-2-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-2.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo Two<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-4-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo Four\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-4-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-4.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo Four<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-3-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo Three\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-3-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-3.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo Three<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-7-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo Seven\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-7-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-7.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo Seven<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-8-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo Eight\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-8-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-8.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo Eight<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-5-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo Five\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-5-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-5.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo Five<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-9-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo Nine\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-9-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-9.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo Nine<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-10-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo Ten\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-10-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-10.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo Ten<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-1-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo One\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-1-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-1.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo One<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-11-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo Eleven\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-11-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-11.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo Eleven<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<a href=\"https:\/\/gsplugins.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"117\" src=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-6-300x117.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"\" title=\"GS Logo Six\" srcset=\"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-6-300x117.png 300w, https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-content\/uploads\/2026\/06\/gs-logo-slider-6.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t<h3 class=\"gs_logo_title\">GS Logo Six<\/h3>\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t\n<\/div>\n\t\t\t\t<!-- Pagination -->\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\n\t\t<style>#gs_logo_area_48:not(.verticaltickerdown):not(.verticalticker) .gs_logo_container{margin-left:-5px}#gs_logo_area_48:not(.verticaltickerdown):not(.verticalticker) .gs_logo_container{margin-right:-5px}#gs_logo_area_48:not(.verticaltickerdown):not(.verticalticker) .gs_logo_single--wrapper{padding:5px}#gs_logo_area_48 ul.gs-logo-filter-cats{text-align:center!important}#gs_logo_area_48 .gs_logo_single--wrapper{width:20%}@media (max-width:1023px){#gs_logo_area_48 .gs_logo_single--wrapper{width:33.333333333333%}}@media (max-width:767px){#gs_logo_area_48 .gs_logo_single--wrapper{width:50%}}<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-cover alignfull has-small-font-size\" style=\"margin-top:var(--wp--preset--spacing--50);margin-bottom:var(--wp--preset--spacing--50);padding-top:var(--wp--preset--spacing--40);padding-right:0;padding-bottom:var(--wp--preset--spacing--40);padding-left:0;min-height:150px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-100 has-background-dim\" style=\"background-color:#2c85e4\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-container-core-cover-is-layout-01fb6936 wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7788c425 wp-block-columns-is-layout-flex\" style=\"padding-right:0;padding-left:0\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-text-align-center has-base-color has-text-color has-link-color has-poppins-font-family has-medium-font-size wp-elements-896450be224f27274b0a8214cb859134 wp-block-paragraph\">2000+ people have put their trust in CCTV, How about you?<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-35f06ea7 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-poppins-font-family has-text-align-center has-small-font-size has-custom-font-size wp-element-button\" style=\"border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px\">Get Started Now<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Embed Google Street View map Contact Information Maecenas nec odio et ante tincidunt tempus. Donec vitae sapien ut libero venenatis faucibus. Nullam quis ante. Etiam sit amet orci eget eros faucibus tincidunt. Duis leo. Sed fringilla mauris sit amet nibh. Donec sodales sagittis magna. Sed consequat, leo. ADDRESS Goldfield Rd.7685 Rock MapleHonolulu, HI 96815 BUSINESS [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-821","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Embed Google Street View map Contact Information Maecenas nec odio et ante tincidunt tempus. Donec vitae sapien ut libero venenatis faucibus. Nullam quis ante. Etiam sit amet orci eget eros faucibus tincidunt. Duis leo. Sed fringilla mauris sit amet nibh. Donec sodales sagittis magna. Sed consequat, leo. ADDRESS Goldfield Rd.7685 Rock MapleHonolulu, HI 96815 BUSINESS&hellip;","_links":{"self":[{"href":"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-json\/wp\/v2\/pages\/821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-json\/wp\/v2\/comments?post=821"}],"version-history":[{"count":16,"href":"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-json\/wp\/v2\/pages\/821\/revisions"}],"predecessor-version":[{"id":906,"href":"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-json\/wp\/v2\/pages\/821\/revisions\/906"}],"wp:attachment":[{"href":"https:\/\/plantilla.logicalwebserver.com\/tecnologia\/theme-01\/wp-json\/wp\/v2\/media?parent=821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}